{"id":73685,"date":"2025-05-09T15:19:13","date_gmt":"2025-05-09T13:19:13","guid":{"rendered":"https:\/\/www.britishschoolbarcelona.com\/?page_id=73685"},"modified":"2025-05-09T15:19:24","modified_gmt":"2025-05-09T13:19:24","slug":"avis-legal","status":"publish","type":"page","link":"https:\/\/www.britishschoolbarcelona.com\/ca\/avis-legal\/","title":{"rendered":"Av\u00eds Legal"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":426,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"legal-notices-es.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-73685","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Av\u00eds Legal - British School of Barcelona<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.britishschoolbarcelona.com\/ca\/avis-legal\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Av\u00eds Legal - British School of Barcelona\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.britishschoolbarcelona.com\/ca\/avis-legal\/\" \/>\n<meta property=\"og:site_name\" content=\"British School of Barcelona\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/britishschoolbarcelonacastelldefels\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-09T13:19:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.britishschoolbarcelona.com\/wp-content\/uploads\/sites\/76\/2024\/06\/bsb-web-imagen-destacada.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@BSB_Barcelona\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Av\u00eds Legal - British School of Barcelona","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.britishschoolbarcelona.com\/ca\/avis-legal\/","og_locale":"ca_ES","og_type":"article","og_title":"Av\u00eds Legal - British School of Barcelona","og_url":"https:\/\/www.britishschoolbarcelona.com\/ca\/avis-legal\/","og_site_name":"British School of Barcelona","article_publisher":"https:\/\/www.facebook.com\/britishschoolbarcelonacastelldefels\/","article_modified_time":"2025-05-09T13:19:24+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.britishschoolbarcelona.com\/wp-content\/uploads\/sites\/76\/2024\/06\/bsb-web-imagen-destacada.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@BSB_Barcelona","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.britishschoolbarcelona.com\/ca\/avis-legal\/","url":"https:\/\/www.britishschoolbarcelona.com\/ca\/avis-legal\/","name":"Av\u00eds Legal - British School of Barcelona","isPartOf":{"@id":"https:\/\/www.britishschoolbarcelona.com\/ca\/#website"},"datePublished":"2025-05-09T13:19:13+00:00","dateModified":"2025-05-09T13:19:24+00:00","breadcrumb":{"@id":"https:\/\/www.britishschoolbarcelona.com\/ca\/avis-legal\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.britishschoolbarcelona.com\/ca\/avis-legal\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.britishschoolbarcelona.com\/ca\/avis-legal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.britishschoolbarcelona.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Av\u00eds Legal"}]},{"@type":"WebSite","@id":"https:\/\/www.britishschoolbarcelona.com\/ca\/#website","url":"https:\/\/www.britishschoolbarcelona.com\/ca\/","name":"British School of Barcelona","description":"The British School of Barcelona is a private international school in Barcelona, Spain. We deliver the British curriculum &amp; IB. Visit us!","publisher":{"@id":"https:\/\/www.britishschoolbarcelona.com\/ca\/#organization"},"alternateName":"BSB","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.britishschoolbarcelona.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/www.britishschoolbarcelona.com\/ca\/#organization","name":"The British School of Barcelona","alternateName":"BSB","url":"https:\/\/www.britishschoolbarcelona.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.britishschoolbarcelona.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/www.britishschoolbarcelona.com\/wp-content\/uploads\/sites\/76\/2023\/01\/BSB-logo.png","contentUrl":"https:\/\/www.britishschoolbarcelona.com\/wp-content\/uploads\/sites\/76\/2023\/01\/BSB-logo.png","width":1920,"height":1357,"caption":"The British School of Barcelona"},"image":{"@id":"https:\/\/www.britishschoolbarcelona.com\/ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/britishschoolbarcelonacastelldefels\/","https:\/\/x.com\/BSB_Barcelona","https:\/\/www.instagram.com\/britishschoolbarcelona\/","https:\/\/www.youtube.com\/channel\/UC-Cc996mIB8CwmapwNYQKvg","https:\/\/es.linkedin.com\/school\/british-school-of-barcelona\/"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.britishschoolbarcelona.com\/ca\/wp-json\/wp\/v2\/pages\/73685","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.britishschoolbarcelona.com\/ca\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.britishschoolbarcelona.com\/ca\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.britishschoolbarcelona.com\/ca\/wp-json\/wp\/v2\/users\/426"}],"replies":[{"embeddable":true,"href":"https:\/\/www.britishschoolbarcelona.com\/ca\/wp-json\/wp\/v2\/comments?post=73685"}],"version-history":[{"count":1,"href":"https:\/\/www.britishschoolbarcelona.com\/ca\/wp-json\/wp\/v2\/pages\/73685\/revisions"}],"predecessor-version":[{"id":73686,"href":"https:\/\/www.britishschoolbarcelona.com\/ca\/wp-json\/wp\/v2\/pages\/73685\/revisions\/73686"}],"wp:attachment":[{"href":"https:\/\/www.britishschoolbarcelona.com\/ca\/wp-json\/wp\/v2\/media?parent=73685"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}