{"id":77657,"date":"2026-05-15T13:25:19","date_gmt":"2026-05-15T11:25:19","guid":{"rendered":"https:\/\/www.britishschoolbarcelona.com\/?post_type=school_news&#038;p=77657"},"modified":"2026-06-04T10:09:11","modified_gmt":"2026-06-04T08:09:11","slug":"un-any-despres-com-bbs-speaks-esta-transformant-la-comunicacio-en-bsb","status":"publish","type":"school_news","link":"https:\/\/www.britishschoolbarcelona.com\/ca\/noticies-escolars\/un-any-despres-com-bbs-speaks-esta-transformant-la-comunicacio-en-bsb\/","title":{"rendered":"Un any despr\u00e9s: Com \u00abBSB Speaks\u00bb est\u00e0 transformant la comunicaci\u00f3 en BSB"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text css=&#8221;&#8221;]Qu\u00e8 passa quan tota una escola deixa de banda els bol\u00edgrafs, tanca els port\u00e0tils i s\u2019enfoca \u00fanicament en el poder de la conversa? Un any despr\u00e9s del llan\u00e7ament del Programa d\u2019Orat\u00f2ria \u00abBSB Speaks\u00bb, el No Pen Morning del 13 de maig va oferir una perspectiva sobre com l\u2019Orat\u00f2ria i l\u2019escolta estan transformant l\u2019aprenentatge en BSB.<\/p>\n<p>Seiem amb el Director Executiu Adjunt James Petrie per reflexionar sobre el recorregut darrere de \u00abBSB Speaks\u00bb, l\u2019impacte que ja t\u00e9 el programa a tota l\u2019escola i per qu\u00e8 l\u2019Orat\u00f2ria importa m\u00e9s que mai al m\u00f3n actual.<\/p>\n<p><strong>Per qu\u00e8 l\u2019Orat\u00f2ria importa m\u00e9s que mai<br \/>\n<\/strong>A The British School of Barcelona, l\u2019Orat\u00f2ria (la capacitat de comunicar-se efica\u00e7ment a trav\u00e9s del llenguatge parlat) es considera una habilitat transformadora per a la vida. El programa \u00abBSB Speaks\u00bb va ser dissenyat per ajudar l\u2019alumnat a convertir-se en comunicadors\/es segurs\/es i eloq\u00fcents, basant-se en investigaci\u00f3 educativa d\u2019avantguarda i adaptant-se espec\u00edficament al context de BSB.<\/p>\n<p>\u00abCom a escola, vam recon\u00e8ixer que la parla i la comunicaci\u00f3 de qualitat mai no han estat m\u00e9s importants \u2014va explicar James Petrie\u2014. En un m\u00f3n on ja no sempre podem confiar plenament en l\u2019escriptura a causa de la intel\u00b7lig\u00e8ncia artificial, la capacitat d\u2019expressar idees amb claredat, honestedat i confian\u00e7a s\u2019est\u00e0 convertint en una cosa essencial\u00bb.<\/p>\n<p>M\u00e9s enll\u00e0 de preparar l\u2019alumnat per a un futur en transformaci\u00f3 constant, el programa tamb\u00e9 s\u2019enfoca en una cosa igualment important: guanyar confian\u00e7a. \u00abAjudar l\u2019alumnat a adaptar el seu llenguatge per a diferents audi\u00e8ncies i prop\u00f2sits no nom\u00e9s els destaca, sin\u00f3 que realment desenvolupa l\u2019autoestima i la confian\u00e7a\u00bb, va destacar.<\/p>\n<p><strong>L\u2019Orat\u00f2ria en acci\u00f3 a tota l\u2019escola<br \/>\n<\/strong>Durant l\u2019any passat, l\u2019Orat\u00f2ria s\u2019ha convertit en part de l\u2019aprenentatge quotidi\u00e0 a tota la escola. A les aules d\u2019Infantil i Prim\u00e0ria, l\u2019alumnat m\u00e9s jove treballa regularment amb \u00abcompanys\/as de conversa\u00bb, utilitzant models de frases per construir respostes m\u00e9s complexes i compartir idees amb confian\u00e7a.<\/p>\n<p>A mesura que l\u2019alumnat avan\u00e7a a l\u2019escola, les discussions es tornen m\u00e9s sofisticades, amb els\/les alumnes assumint rols com a \u00abdinamitzador\/a\u00bb o \u00abresumidor\/a\u00bb dins de converses en grup. L\u2019alumnat gran est\u00e0 aprenent a realitzar presentacions, impartir lli\u00e7ons ells\/es mateixos\/es i preparar-se per als desafiaments de comunicaci\u00f3 en el m\u00f3n real.<\/p>\n<p>\u00abJa estem planificant la introducci\u00f3 de sessions sobre <em>networking,<\/em> mantenir converses informals i habilitats d\u2019entrevista \u2014diu Petrie\u2014. Aquestes s\u00f3n habilitats per al futur de qu\u00e8 el nostre alumnat realment se\u2019n beneficiar\u00e0\u00bb.<\/p>\n<p>En lloc de basar-se en qualificacions o notes, el programa se centra en el progr\u00e9s, la cr\u00edtica constructiva i guanyar confian\u00e7a. Els\/Les docents utilitzen mapes de progr\u00e9s per curs per garantir que les habilitats d\u2019expressi\u00f3 oral es desenvolupin consistentment en cada etapa de la vida escolar.<\/p>\n<p>\u00abNo veiem aix\u00f2 com donar punts per parlar \u2014explica Petrie\u2014. Es tracta d\u2019oferir observacions honestes i \u00fatils per ajudar els\/les alumnes a creure en si mateixos\/es. Cada alumne\/a t\u00e9 el potencial de convertir-se en un\/a gran orador\/a\u00bb.[\/vc_column_text][vc_column_text css=&#8221;&#8221;]<\/p>\n<p><iframe loading=\"lazy\" title=\"No Pen Morning | &amp;apos;BSB Speaks&amp;apos; Oracy Programme | 2026\" width=\"1140\" height=\"641\" src=\"https:\/\/www.youtube.com\/embed\/xin5vOlArR4?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>[\/vc_column_text][vc_column_text css=&#8221;&#8221;]<strong>Guanyar confian\u00e7a i protagonisme de l\u2019alumnat<br \/>\n<\/strong>L\u2019impacte de \u00abBSB Speaks\u00bb ja \u00e9s visible a tota la comunitat educativa. L\u2019alumnat ha presentat assemblees, s\u2019ha dirigit a les fam\u00edlies i, fins i tot, ha assumit papers de lideratge durant No Pen Morning.<\/p>\n<p>\u00abConsiderant que el programa ha funcionat nom\u00e9s aquest curs, la resposta ha estat incre\u00efblement positiva \u2014diu Petrie\u2014. L\u2019alumnat pot sentir genu\u00efnament el progr\u00e9s que est\u00e0 fent\u00bb.<\/p>\n<p>Un dels exemples m\u00e9s clars va sorgir durant No Pen Morning, quan l\u2019alumnat m\u00e9s gran de Years 10, 11 i 12 va dirigir tallers d\u2019Art Dram\u00e0tic per a l\u2019alumnat m\u00e9s jove. \u00ab\u00c9s un desafiament enorme per a ells\/es, per\u00f2 tamb\u00e9 una oportunitat fant\u00e0stica \u2014diu Petrie\u2014. Tots\/es estan realment emocionats\/des amb aix\u00f2\u00bb.<\/p>\n<p><strong>El No Pen Morning de BSB per dins<br \/>\n<\/strong>Lluny de ser un esdeveniment a\u00efllat, No Pen Morning va ser dissenyat com una celebraci\u00f3 de tot all\u00f2 que \u00abBSB Speaks\u00bb ha introdu\u00eft al llarg de l\u2019any. Durant totes les lli\u00e7ons matutines (des d\u2019Infantil fins a Year 10), es van deixar de banda els bol\u00edgrafs, els port\u00e0tils i el treball escrit a favor de l\u2019aprenentatge basat en la conversa i les activitats orals col\u00b7laboratives.<\/p>\n<p>\u00abLa idea va ser crear lli\u00e7ons constru\u00efdes purament al voltant de la conversa \u2014explica Petrie\u2014. Es va animar els\/les docents a experimentar, a provar alguna cosa nova i a explorar com l\u2019orat\u00f2ria pot impulsar l\u2019aprenentatge a totes les assignatures\u00bb.<\/p>\n<p>Entre bastidors, la iniciativa ha estat acuradament desenvolupada per un grup de treball \u00abBSB Speaks\u00bb de l\u2019escola, integrat per docents de diferents cursos i etapes. La seva funci\u00f3 ha estat garantir que les activitats siguin tant apropiades per a l\u2019edat de l\u2019alumnat com desafiants per a tots els cursos.<\/p>\n<p><strong>Preparar els\/les alumnes per al futur<br \/>\n<\/strong>De cara al futur, Petrie espera que l\u2019alumnat se\u2019n vagi no nom\u00e9s amb habilitats de comunicaci\u00f3 oral m\u00e9s s\u00f2lides, sin\u00f3 amb una comprensi\u00f3 m\u00e9s profunda de per qu\u00e8 aquestes habilitats importen. \u00abVolem que l\u2019alumnat es vagi guanyant confian\u00e7a en les seves pr\u00f2pies capacitats i amb una consci\u00e8ncia de com \u00e9s d\u2019important la comunicaci\u00f3 no nom\u00e9s ara, sin\u00f3 al llarg de la seva vida\u00bb.<\/p>\n<p>Aquest missatge sembla especialment significatiu al m\u00f3n cada cop m\u00e9s digital d\u2019avui. \u00abA difer\u00e8ncia de la comunicaci\u00f3 a trav\u00e9s de la intel\u00b7lig\u00e8ncia artificial o les pantalles, parlar amb alg\u00fa amb claredat i honestedat (i escoltar amb respecte i sensibilitat) ens permet fer connexions humanes genu\u00efnes \u2014reflexiona Petrie\u2014. Aix\u00f2 \u00e9s una cosa incre\u00efblement important per a tots nosaltres avui\u00bb.<\/p>\n<p><strong>Una part clau de la visi\u00f3 de BSB<br \/>\n<\/strong>L\u2019Orat\u00f2ria continua sent una de les prioritats centrals dins del <a href=\"https:\/\/www.britishschoolbarcelona.com\/ca\/pla-desenvolupament-escolar\/\"><strong>Pla de Desenvolupament a tres anys<\/strong><\/a> de BSB, amb la formaci\u00f3 del personal i el desenvolupament professional continuant enfocant-se fortament a consolidar el programa \u00abBSB Speaks\u00bb a tota la comunitat educativa.<\/p>\n<p>Podeu obtenir m\u00e9s informaci\u00f3 al <a href=\"https:\/\/www.canva.com\/design\/DAG5CYmV4QI\/MFh78jvAlGq6pLVBetv05A\/view?utm_content=DAG5CYmV4QI&amp;utm_campaign=designshare&amp;utm_medium=link2&amp;utm_source=uniquelinks&amp;utlId=h0b25eb5503\"><strong>fullet del Programa d\u2019Orat\u00f2ria \u00abBSB Speaks\u00bb<\/strong><\/a> i veure el llan\u00e7ament del programa original al nostre canal de <a href=\"https:\/\/www.youtube.com\/watch?v=2zFXKFwk320&amp;utm_source=chatgpt.com\"><strong>YouTube<\/strong><\/a><strong>.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Not\u00edcies relacionades:<\/strong><\/p>\n<p><a href=\"https:\/\/www.britishschoolbarcelona.com\/ca\/noticies-escolars\/estudiants-de-bsb-demostren-les-seves-habilitats-de-bsb-speaks-al-harvard-model-congress-europe-2026\/\"><strong>Estudiants de BSB demostren les seves habilitats de \u00abBSB Speaks\u00bb al Harvard Model Congress Europe 2026<\/strong><\/a><\/p>\n<p><a href=\"https:\/\/www.britishschoolbarcelona.com\/ca\/noticies-escolars\/estudiants-de-bsb-nexus-participen-en-la-lliga-catalana-de-debat-a-la-uab\/\"><strong>Estudiants de BSB Nexus participen en la Lliga Catalana de Debat a la UAB<\/strong><\/a>[\/vc_column_text]<section  class=\"section  container-width    \" style=''>\n                        <div class=\"container-fluid pt-0\">       <div class=\"row m-0 align-items-center centerText\">\n                                <div class=\"col-sm-12 col-md-12 col-lg-10 mx-auto\">            <\/div>\n                            <\/div><div class=\"row m-0 mt-5\">\n                                <div class=\"col-md-11 col-lg-11 col-xl-12 mx-auto  p-0 px-md-3\">\n                                    <div class=\"component slick-carousel\">\n                                        <div class=\"component slick-carousel\">\n                                            <div class=\"slick-slider--with-icon slick-slider full--slider\"><div>\n                                               \n                                                    <div class=\"component single-img\">\n                                                        <div class=\"callout-img leftBottom-content\" style=\"background-image: url('https:\/\/www.britishschoolbarcelona.com\/wp-content\/uploads\/sites\/76\/2026\/05\/no-pen-day-1.png');\">\n                                                        <\/div>                                \n                                                    <\/div>\n                                                    <div class=\"component sub-heading\">\n                                                        <figcaption><\/figcaption>\n                                                    <\/div>\n                                                <\/div><div>\n                                               \n                                                    <div class=\"component single-img\">\n                                                        <div class=\"callout-img leftBottom-content\" style=\"background-image: url('https:\/\/www.britishschoolbarcelona.com\/wp-content\/uploads\/sites\/76\/2026\/05\/no-pen-day-2.png');\">\n                                                        <\/div>                                \n                                                    <\/div>\n                                                    <div class=\"component sub-heading\">\n                                                        <figcaption><\/figcaption>\n                                                    <\/div>\n                                                <\/div><div>\n                                               \n                                                    <div class=\"component single-img\">\n                                                        <div class=\"callout-img leftBottom-content\" style=\"background-image: url('https:\/\/www.britishschoolbarcelona.com\/wp-content\/uploads\/sites\/76\/2026\/05\/no-pen-day-3.png');\">\n                                                        <\/div>                                \n                                                    <\/div>\n                                                    <div class=\"component sub-heading\">\n                                                        <figcaption><\/figcaption>\n                                                    <\/div>\n                                                <\/div><div>\n                                               \n                                                    <div class=\"component single-img\">\n                                                        <div class=\"callout-img leftBottom-content\" style=\"background-image: url('https:\/\/www.britishschoolbarcelona.com\/wp-content\/uploads\/sites\/76\/2026\/05\/no-pen-day-4.png');\">\n                                                        <\/div>                                \n                                                    <\/div>\n                                                    <div class=\"component sub-heading\">\n                                                        <figcaption><\/figcaption>\n                                                    <\/div>\n                                                <\/div><div>\n                                               \n                                                    <div class=\"component single-img\">\n                                                        <div class=\"callout-img leftBottom-content\" style=\"background-image: url('https:\/\/www.britishschoolbarcelona.com\/wp-content\/uploads\/sites\/76\/2026\/05\/no-pen-day-5.png');\">\n                                                        <\/div>                                \n                                                    <\/div>\n                                                    <div class=\"component sub-heading\">\n                                                        <figcaption><\/figcaption>\n                                                    <\/div>\n                                                <\/div><div>\n                                               \n                                                    <div class=\"component single-img\">\n                                                        <div class=\"callout-img leftBottom-content\" style=\"background-image: url('https:\/\/www.britishschoolbarcelona.com\/wp-content\/uploads\/sites\/76\/2026\/05\/no-pen-day-6.png');\">\n                                                        <\/div>                                \n                                                    <\/div>\n                                                    <div class=\"component sub-heading\">\n                                                        <figcaption><\/figcaption>\n                                                    <\/div>\n                                                <\/div><div>\n                                               \n                                                    <div class=\"component single-img\">\n                                                        <div class=\"callout-img leftBottom-content\" style=\"background-image: url('https:\/\/www.britishschoolbarcelona.com\/wp-content\/uploads\/sites\/76\/2026\/05\/no-pen-day-7.png');\">\n                                                        <\/div>                                \n                                                    <\/div>\n                                                    <div class=\"component sub-heading\">\n                                                        <figcaption><\/figcaption>\n                                                    <\/div>\n                                                <\/div><div>\n                                               \n                                                    <div class=\"component single-img\">\n                                                        <div class=\"callout-img leftBottom-content\" style=\"background-image: url('https:\/\/www.britishschoolbarcelona.com\/wp-content\/uploads\/sites\/76\/2026\/05\/no-pen-day-8.png');\">\n                                                        <\/div>                                \n                                                    <\/div>\n                                                    <div class=\"component sub-heading\">\n                                                        <figcaption><\/figcaption>\n                                                    <\/div>\n                                                <\/div><div>\n                                               \n                                                    <div class=\"component single-img\">\n                                                        <div class=\"callout-img leftBottom-content\" style=\"background-image: url('https:\/\/www.britishschoolbarcelona.com\/wp-content\/uploads\/sites\/76\/2026\/05\/no-pen-day-9.png');\">\n                                                        <\/div>                                \n                                                    <\/div>\n                                                    <div class=\"component sub-heading\">\n                                                        <figcaption><\/figcaption>\n                                                    <\/div>\n                                                <\/div><\/div>\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n    \n                    <\/section>[\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Qu\u00e8 passa quan tota una escola deixa de banda els bol\u00edgrafs, tanca els port\u00e0tils i s\u2019enfoca \u00fanicament en el poder de la conversa? Un any despr\u00e9s del llan\u00e7ament del Programa d\u2019Orat\u00f2ria \u00abBSB Speaks\u00bb, el No Pen Morning del 13 de maig va oferir una perspectiva sobre com l\u2019Orat\u00f2ria i l\u2019escolta estan transformant l\u2019aprenentatge en BSB.<\/p>\n","protected":false},"author":480,"featured_media":77627,"parent":0,"menu_order":0,"template":"","meta":{"_acf_changed":false,"footnotes":""},"news-category":[738],"news-tag":[1169,1190],"class_list":["post-77657","school_news","type-school_news","status-publish","has-post-thumbnail","hentry","news-category-vida-escolar-ca","news-tag-bsb-speaks","news-tag-no-pen-day"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Un any despr\u00e9s: Com \u00abBSB Speaks\u00bb est\u00e0 transformant la comunicaci\u00f3 en BSB - British School of Barcelona<\/title>\n<meta name=\"description\" content=\"Qu\u00e8 passa quan tota una escola deixa de banda els bol\u00edgrafs, tanca els port\u00e0tils i s\u2019enfoca \u00fanicament en el poder de la conversa? Un any despr\u00e9s del llan\u00e7ament del Programa d\u2019Orat\u00f2ria \u00abBSB Speaks\u00bb, el No Pen Morning del 13 de maig va oferir una perspectiva sobre com l\u2019Orat\u00f2ria i l\u2019escolta estan transformant l\u2019aprenentatge en BSB.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.britishschoolbarcelona.com\/ca\/noticies-escolars\/un-any-despres-com-bbs-speaks-esta-transformant-la-comunicacio-en-bsb\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un any despr\u00e9s: Com \u00abBSB Speaks\u00bb est\u00e0 transformant la comunicaci\u00f3 en BSB - British School of Barcelona\" \/>\n<meta property=\"og:description\" content=\"Qu\u00e8 passa quan tota una escola deixa de banda els bol\u00edgrafs, tanca els port\u00e0tils i s\u2019enfoca \u00fanicament en el poder de la conversa? Un any despr\u00e9s del llan\u00e7ament del Programa d\u2019Orat\u00f2ria \u00abBSB Speaks\u00bb, el No Pen Morning del 13 de maig va oferir una perspectiva sobre com l\u2019Orat\u00f2ria i l\u2019escolta estan transformant l\u2019aprenentatge en BSB.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.britishschoolbarcelona.com\/ca\/noticies-escolars\/un-any-despres-com-bbs-speaks-esta-transformant-la-comunicacio-en-bsb\/\" \/>\n<meta property=\"og:site_name\" content=\"British School of Barcelona\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/britishschoolbarcelonacastelldefels\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-04T08:09:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.britishschoolbarcelona.com\/wp-content\/uploads\/sites\/76\/2026\/05\/No-Pen-Day.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1116\" \/>\n\t<meta property=\"og:image:height\" content=\"550\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@BSB_Barcelona\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un any despr\u00e9s: Com \u00abBSB Speaks\u00bb est\u00e0 transformant la comunicaci\u00f3 en BSB - British School of Barcelona","description":"Qu\u00e8 passa quan tota una escola deixa de banda els bol\u00edgrafs, tanca els port\u00e0tils i s\u2019enfoca \u00fanicament en el poder de la conversa? Un any despr\u00e9s del llan\u00e7ament del Programa d\u2019Orat\u00f2ria \u00abBSB Speaks\u00bb, el No Pen Morning del 13 de maig va oferir una perspectiva sobre com l\u2019Orat\u00f2ria i l\u2019escolta estan transformant l\u2019aprenentatge en BSB.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.britishschoolbarcelona.com\/ca\/noticies-escolars\/un-any-despres-com-bbs-speaks-esta-transformant-la-comunicacio-en-bsb\/","og_locale":"ca_ES","og_type":"article","og_title":"Un any despr\u00e9s: Com \u00abBSB Speaks\u00bb est\u00e0 transformant la comunicaci\u00f3 en BSB - British School of Barcelona","og_description":"Qu\u00e8 passa quan tota una escola deixa de banda els bol\u00edgrafs, tanca els port\u00e0tils i s\u2019enfoca \u00fanicament en el poder de la conversa? Un any despr\u00e9s del llan\u00e7ament del Programa d\u2019Orat\u00f2ria \u00abBSB Speaks\u00bb, el No Pen Morning del 13 de maig va oferir una perspectiva sobre com l\u2019Orat\u00f2ria i l\u2019escolta estan transformant l\u2019aprenentatge en BSB.","og_url":"https:\/\/www.britishschoolbarcelona.com\/ca\/noticies-escolars\/un-any-despres-com-bbs-speaks-esta-transformant-la-comunicacio-en-bsb\/","og_site_name":"British School of Barcelona","article_publisher":"https:\/\/www.facebook.com\/britishschoolbarcelonacastelldefels\/","article_modified_time":"2026-06-04T08:09:11+00:00","og_image":[{"width":1116,"height":550,"url":"https:\/\/www.britishschoolbarcelona.com\/wp-content\/uploads\/sites\/76\/2026\/05\/No-Pen-Day.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@BSB_Barcelona","twitter_misc":{"Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.britishschoolbarcelona.com\/ca\/noticies-escolars\/un-any-despres-com-bbs-speaks-esta-transformant-la-comunicacio-en-bsb\/#article","isPartOf":{"@id":"https:\/\/www.britishschoolbarcelona.com\/ca\/noticies-escolars\/un-any-despres-com-bbs-speaks-esta-transformant-la-comunicacio-en-bsb\/"},"author":{"name":"alejandroarraez","@id":"https:\/\/www.britishschoolbarcelona.com\/ca\/#\/schema\/person\/795d1b75cffe8dc803898f92e5bd0549"},"headline":"Un any despr\u00e9s: Com \u00abBSB Speaks\u00bb est\u00e0 transformant la comunicaci\u00f3 en BSB","datePublished":"2026-05-15T11:25:19+00:00","dateModified":"2026-06-04T08:09:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.britishschoolbarcelona.com\/ca\/noticies-escolars\/un-any-despres-com-bbs-speaks-esta-transformant-la-comunicacio-en-bsb\/"},"wordCount":1260,"publisher":{"@id":"https:\/\/www.britishschoolbarcelona.com\/ca\/#organization"},"image":{"@id":"https:\/\/www.britishschoolbarcelona.com\/ca\/noticies-escolars\/un-any-despres-com-bbs-speaks-esta-transformant-la-comunicacio-en-bsb\/#primaryimage"},"thumbnailUrl":"https:\/\/www.britishschoolbarcelona.com\/wp-content\/uploads\/sites\/76\/2026\/05\/No-Pen-Day.png","inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/www.britishschoolbarcelona.com\/ca\/noticies-escolars\/un-any-despres-com-bbs-speaks-esta-transformant-la-comunicacio-en-bsb\/","url":"https:\/\/www.britishschoolbarcelona.com\/ca\/noticies-escolars\/un-any-despres-com-bbs-speaks-esta-transformant-la-comunicacio-en-bsb\/","name":"Un any despr\u00e9s: Com \u00abBSB Speaks\u00bb est\u00e0 transformant la comunicaci\u00f3 en BSB - British School of Barcelona","isPartOf":{"@id":"https:\/\/www.britishschoolbarcelona.com\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.britishschoolbarcelona.com\/ca\/noticies-escolars\/un-any-despres-com-bbs-speaks-esta-transformant-la-comunicacio-en-bsb\/#primaryimage"},"image":{"@id":"https:\/\/www.britishschoolbarcelona.com\/ca\/noticies-escolars\/un-any-despres-com-bbs-speaks-esta-transformant-la-comunicacio-en-bsb\/#primaryimage"},"thumbnailUrl":"https:\/\/www.britishschoolbarcelona.com\/wp-content\/uploads\/sites\/76\/2026\/05\/No-Pen-Day.png","datePublished":"2026-05-15T11:25:19+00:00","dateModified":"2026-06-04T08:09:11+00:00","description":"Qu\u00e8 passa quan tota una escola deixa de banda els bol\u00edgrafs, tanca els port\u00e0tils i s\u2019enfoca \u00fanicament en el poder de la conversa? Un any despr\u00e9s del llan\u00e7ament del Programa d\u2019Orat\u00f2ria \u00abBSB Speaks\u00bb, el No Pen Morning del 13 de maig va oferir una perspectiva sobre com l\u2019Orat\u00f2ria i l\u2019escolta estan transformant l\u2019aprenentatge en BSB.","breadcrumb":{"@id":"https:\/\/www.britishschoolbarcelona.com\/ca\/noticies-escolars\/un-any-despres-com-bbs-speaks-esta-transformant-la-comunicacio-en-bsb\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.britishschoolbarcelona.com\/ca\/noticies-escolars\/un-any-despres-com-bbs-speaks-esta-transformant-la-comunicacio-en-bsb\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.britishschoolbarcelona.com\/ca\/noticies-escolars\/un-any-despres-com-bbs-speaks-esta-transformant-la-comunicacio-en-bsb\/#primaryimage","url":"https:\/\/www.britishschoolbarcelona.com\/wp-content\/uploads\/sites\/76\/2026\/05\/No-Pen-Day.png","contentUrl":"https:\/\/www.britishschoolbarcelona.com\/wp-content\/uploads\/sites\/76\/2026\/05\/No-Pen-Day.png","width":1116,"height":550},{"@type":"BreadcrumbList","@id":"https:\/\/www.britishschoolbarcelona.com\/ca\/noticies-escolars\/un-any-despres-com-bbs-speaks-esta-transformant-la-comunicacio-en-bsb\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.britishschoolbarcelona.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Noticies Escolars","item":"https:\/\/www.britishschoolbarcelona.com\/ca\/noticies-escolars\/"},{"@type":"ListItem","position":3,"name":"Un any despr\u00e9s: Com \u00abBSB Speaks\u00bb est\u00e0 transformant la comunicaci\u00f3 en BSB"}]},{"@type":"WebSite","@id":"https:\/\/www.britishschoolbarcelona.com\/ca\/#website","url":"https:\/\/www.britishschoolbarcelona.com\/ca\/","name":"British School of Barcelona","description":"The British School of Barcelona is a private international school in Barcelona, Spain. We deliver the British curriculum &amp; IB. Visit us!","publisher":{"@id":"https:\/\/www.britishschoolbarcelona.com\/ca\/#organization"},"alternateName":"BSB","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.britishschoolbarcelona.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/www.britishschoolbarcelona.com\/ca\/#organization","name":"The British School of Barcelona","alternateName":"BSB","url":"https:\/\/www.britishschoolbarcelona.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.britishschoolbarcelona.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/www.britishschoolbarcelona.com\/wp-content\/uploads\/sites\/76\/2023\/01\/BSB-logo.png","contentUrl":"https:\/\/www.britishschoolbarcelona.com\/wp-content\/uploads\/sites\/76\/2023\/01\/BSB-logo.png","width":1920,"height":1357,"caption":"The British School of Barcelona"},"image":{"@id":"https:\/\/www.britishschoolbarcelona.com\/ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/britishschoolbarcelonacastelldefels\/","https:\/\/x.com\/BSB_Barcelona","https:\/\/www.instagram.com\/britishschoolbarcelona\/","https:\/\/www.youtube.com\/channel\/UC-Cc996mIB8CwmapwNYQKvg","https:\/\/es.linkedin.com\/school\/british-school-of-barcelona\/"]},{"@type":"Person","@id":"https:\/\/www.britishschoolbarcelona.com\/ca\/#\/schema\/person\/795d1b75cffe8dc803898f92e5bd0549","name":"alejandroarraez","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/secure.gravatar.com\/avatar\/340d82f184ee74afef95c58a3c8b8aaccf3c9236f188fda15f2c3bc5c4f6e340?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/340d82f184ee74afef95c58a3c8b8aaccf3c9236f188fda15f2c3bc5c4f6e340?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/340d82f184ee74afef95c58a3c8b8aaccf3c9236f188fda15f2c3bc5c4f6e340?s=96&d=mm&r=g","caption":"alejandroarraez"},"url":"https:\/\/www.britishschoolbarcelona.com\/ca\/author\/alejandroarraez\/"}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.britishschoolbarcelona.com\/ca\/wp-json\/wp\/v2\/school_news\/77657","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.britishschoolbarcelona.com\/ca\/wp-json\/wp\/v2\/school_news"}],"about":[{"href":"https:\/\/www.britishschoolbarcelona.com\/ca\/wp-json\/wp\/v2\/types\/school_news"}],"author":[{"embeddable":true,"href":"https:\/\/www.britishschoolbarcelona.com\/ca\/wp-json\/wp\/v2\/users\/480"}],"version-history":[{"count":6,"href":"https:\/\/www.britishschoolbarcelona.com\/ca\/wp-json\/wp\/v2\/school_news\/77657\/revisions"}],"predecessor-version":[{"id":77811,"href":"https:\/\/www.britishschoolbarcelona.com\/ca\/wp-json\/wp\/v2\/school_news\/77657\/revisions\/77811"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.britishschoolbarcelona.com\/ca\/wp-json\/wp\/v2\/media\/77627"}],"wp:attachment":[{"href":"https:\/\/www.britishschoolbarcelona.com\/ca\/wp-json\/wp\/v2\/media?parent=77657"}],"wp:term":[{"taxonomy":"news-category","embeddable":true,"href":"https:\/\/www.britishschoolbarcelona.com\/ca\/wp-json\/wp\/v2\/news-category?post=77657"},{"taxonomy":"news-tag","embeddable":true,"href":"https:\/\/www.britishschoolbarcelona.com\/ca\/wp-json\/wp\/v2\/news-tag?post=77657"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}