{"id":77849,"date":"2026-06-05T12:53:40","date_gmt":"2026-06-05T10:53:40","guid":{"rendered":"https:\/\/www.britishschoolbarcelona.com\/?post_type=school_news&#038;p=77849"},"modified":"2026-06-05T12:53:42","modified_gmt":"2026-06-05T10:53:42","slug":"creando-un-futuro-sostenible-el-camino-de-bsb","status":"publish","type":"school_news","link":"https:\/\/www.britishschoolbarcelona.com\/es\/noticias-escolares\/creando-un-futuro-sostenible-el-camino-de-bsb\/","title":{"rendered":"Creando un futuro sostenible: el camino de BSB"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text css=&#8221;&#8221;]Hoy en d\u00eda, los colegios equilibran una amplia gama de prioridades, desde los logros acad\u00e9micos y el bienestar del alumnado hasta la transformaci\u00f3n digital y la preparaci\u00f3n para el futuro. Sin embargo, en este mundo en constante cambio, la sostenibilidad ya no es opcional, sino esencial, tanto para los colegios como para el alumnado que preparan para el futuro.<\/p>\n<p>En <a href=\"https:\/\/www.britishschoolbarcelona.com\/es\/\"><strong>The British School of Barcelona<\/strong><\/a>\u00a0reconocemos que nuestro alumnado ya se ve afectado por el cambio clim\u00e1tico y debe estar equipado con las habilidades y la mentalidad necesarias para prosperar en un mundo m\u00e1s sostenible.<\/p>\n<p>Durante el \u00faltimo a\u00f1o, la sostenibilidad se ha convertido en una prioridad estrat\u00e9gica clave. Hemos constituido un Equipo de Acci\u00f3n por la Sostenibilidad, nombrado responsables de campus y ampliado iniciativas lideradas por el alumnado, con estudiantes contribuyendo activamente a trav\u00e9s de campa\u00f1as de reducci\u00f3n de energ\u00eda, proyectos de gesti\u00f3n de residuos y actividades de compromiso con la comunidad.<\/p>\n<p><strong>Trabajo colaborativo<br \/>\n<\/strong>Una parte clave de nuestro camino ha sido nuestra asociaci\u00f3n con <a href=\"https:\/\/www.sustainabilityatschool.org\/\" target=\"_blank\" rel=\"noopener\"><strong>Sustainability at School<\/strong><\/a><strong>,<\/strong> una organizaci\u00f3n enfocada en reducir el impacto ambiental de los colegios mientras desarrolla liderazgo en sostenibilidad entre el alumnado y el profesorado.<\/p>\n<p>Juntos\/as, hemos identificado \u00e1reas prioritarias, apoyado iniciativas lideradas por el alumnado y registrado el impacto en los distintos campus, integrando la sostenibilidad en la vida diaria del colegio y aline\u00e1ndola con nuestra estrategia a largo plazo.<\/p>\n<p>El director ejecutivo Neil Tetley y Clare Garey, fundadora de Sustainability at School, compartir\u00e1n tambi\u00e9n el impacto de este trabajo el 13 de junio en el Festival of Education Spain, demostrando c\u00f3mo un enfoque estrat\u00e9gico integral puede impulsar cambios significativos y capacitar al alumnado para convertirse en agentes de cambio del futuro.<\/p>\n<p><strong>\u00c1reas principales<br \/>\n<\/strong>Nuestro enfoque inicial fue reducir el consumo de energ\u00eda, con el alumnado liderando auditor\u00edas y campa\u00f1as como Race to Zero y Cool &amp; Conscious para monitorizar y reducir su uso.<\/p>\n<p>Este a\u00f1o, el enfoque se ha desplazado hacia la reducci\u00f3n de residuos y el fomento de la reutilizaci\u00f3n, yendo m\u00e1s all\u00e1 del reciclaje para abordar los h\u00e1bitos de consumo de manera m\u00e1s directa. Estos esfuerzos ya han resultado en que casi cuatrocientos art\u00edculos de ropa hayan sido reutilizados, promoviendo el pensamiento de econom\u00eda circular en nuestra comunidad educativa.<\/p>\n<p>Junto a estas iniciativas, hemos introducido mejoras operativas en todos los campus, incluyendo la reducci\u00f3n de pl\u00e1sticos de un solo uso, la mejora de sistemas de alimentaci\u00f3n, la introducci\u00f3n de materiales biodegradables y la adopci\u00f3n de alternativas m\u00e1s sostenibles en las operaciones diarias.<\/p>\n<p><strong>Hitos principales<br \/>\n<\/strong>Nuestras iniciativas de sostenibilidad ya han logrado resultados significativos en toda la comunidad escolar:<\/p>\n<ul>\n<li>Reducci\u00f3n del 7\u00a0% en el consumo de electricidad, ahorrando m\u00e1s de 68\u00a0000 kWh y evitando doce toneladas de emisiones de CO\u2082e.<\/li>\n<li>Casi cuatrocientos art\u00edculos de ropa y libros reutilizados a trav\u00e9s de intercambios.<\/li>\n<li>Residuos alimentarios reducidos de treinta y dos kg a diecinueve kg por d\u00eda en campa\u00f1as a corto plazo.<\/li>\n<li>Reducci\u00f3n de impresiones por estudiante comparado con el curso anterior.<\/li>\n<li>Miles de pl\u00e1sticos de un solo uso evitados, incluyendo 257\u00a0000 envases de yogur, 13\u00a0000 botellas de agua de pl\u00e1stico y 18\u00a0000 c\u00e1psulas de caf\u00e9 no reciclables cada a\u00f1o.<\/li>\n<\/ul>\n<p><strong>Un colegio preparado para el futuro<br \/>\n<\/strong>Mirando hacia el futuro, la sostenibilidad se est\u00e1 integrando en el aprendizaje a trav\u00e9s de un nuevo curr\u00edculo de <a href=\"https:\/\/www.britishschoolbarcelona.com\/es\/primaria\/\"><strong>Primaria<\/strong><\/a> que empezar\u00e1 en septiembre. Construido en torno a la Alfabetizaci\u00f3n Digital, el Emprendimiento y los Futuros Globales, el curr\u00edculo integra la sostenibilidad en todas las asignaturas y anima al alumnado a explorar soluciones a los desaf\u00edos globales a trav\u00e9s de la acci\u00f3n pr\u00e1ctica.<\/p>\n<p>El alumnado tambi\u00e9n ha participado en limpiezas de playas en Sitges, Castelldefels y Barcelona, obteniendo experiencia directa de los desaf\u00edos ambientales y el impacto de la acci\u00f3n colectiva.<\/p>\n<p>Este compromiso se extender\u00e1 a nuestro pr\u00f3ximo campus de <a href=\"https:\/\/www.britishschoolbarcelona.com\/es\/instalaciones-y-ubicacion\/bsb-maresme\/\"><strong>BSB Maresme<\/strong><\/a><strong>,<\/strong> que abrir\u00e1 en septiembre del 2026 y ha sido dise\u00f1ado con la sostenibilidad como parte de su eje central.<\/p>\n<p>En conjunto, estas iniciativas reflejan nuestro compromiso de preparar al alumnado no solo para el \u00e9xito acad\u00e9mico, sino tambi\u00e9n para convertirse en ciudadanos\/as globales responsables, informados\/as y proactivos\/as, listos\/as para construir un futuro m\u00e1s sostenible tanto dentro como fuera de las aulas de BSB.<\/p>\n<p><strong>Un a\u00f1o en revisi\u00f3n<br \/>\n<\/strong>Aqu\u00ed ten\u00e9is disponible un informe m\u00e1s detallado sobre todas las acciones de sostenibilidad: <a href=\"https:\/\/www.canva.com\/design\/DAHEYcFI2n4\/18x7-2vII-PSlt-JEP1jNg\/view?utm_content=DAHEYcFI2n4&amp;utm_campaign=designshare&amp;utm_medium=link2&amp;utm_source=uniquelinks&amp;utlId=h22f81e4c87\"><strong>Nuestro progreso en sostenibilidad<\/strong><\/a>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>En BSB reconocemos que nuestro alumnado ya se ve afectado por el cambio clim\u00e1tico y debe estar equipado con las habilidades y la mentalidad necesarias para prosperar en un mundo m\u00e1s sostenible.<\/p>\n","protected":false},"author":480,"featured_media":77846,"parent":0,"menu_order":0,"template":"","meta":{"_acf_changed":false,"footnotes":""},"news-category":[746],"news-tag":[1100],"class_list":["post-77849","school_news","type-school_news","status-publish","has-post-thumbnail","hentry","news-category-vida-escolar-es","news-tag-sustainability-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Creando un futuro sostenible: el camino de BSB - British School of Barcelona<\/title>\n<meta name=\"description\" content=\"En The British School of Barcelona reconocemos que nuestro alumnado ya se ve afectado por el cambio clim\u00e1tico y debe estar equipado con las habilidades y la mentalidad necesarias para prosperar en un mundo m\u00e1s sostenible.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.britishschoolbarcelona.com\/es\/noticias-escolares\/creando-un-futuro-sostenible-el-camino-de-bsb\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Creando un futuro sostenible: el camino de BSB - British School of Barcelona\" \/>\n<meta property=\"og:description\" content=\"En The British School of Barcelona reconocemos que nuestro alumnado ya se ve afectado por el cambio clim\u00e1tico y debe estar equipado con las habilidades y la mentalidad necesarias para prosperar en un mundo m\u00e1s sostenible.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.britishschoolbarcelona.com\/es\/noticias-escolares\/creando-un-futuro-sostenible-el-camino-de-bsb\/\" \/>\n<meta property=\"og:site_name\" content=\"British School of Barcelona\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/britishschoolbarcelonacastelldefels\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-05T10:53:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.britishschoolbarcelona.com\/wp-content\/uploads\/sites\/76\/2026\/06\/eco-comms.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1116\" \/>\n\t<meta property=\"og:image:height\" content=\"550\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@BSB_Barcelona\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Creando un futuro sostenible: el camino de BSB - British School of Barcelona","description":"En The British School of Barcelona reconocemos que nuestro alumnado ya se ve afectado por el cambio clim\u00e1tico y debe estar equipado con las habilidades y la mentalidad necesarias para prosperar en un mundo m\u00e1s sostenible.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.britishschoolbarcelona.com\/es\/noticias-escolares\/creando-un-futuro-sostenible-el-camino-de-bsb\/","og_locale":"es_ES","og_type":"article","og_title":"Creando un futuro sostenible: el camino de BSB - British School of Barcelona","og_description":"En The British School of Barcelona reconocemos que nuestro alumnado ya se ve afectado por el cambio clim\u00e1tico y debe estar equipado con las habilidades y la mentalidad necesarias para prosperar en un mundo m\u00e1s sostenible.","og_url":"https:\/\/www.britishschoolbarcelona.com\/es\/noticias-escolares\/creando-un-futuro-sostenible-el-camino-de-bsb\/","og_site_name":"British School of Barcelona","article_publisher":"https:\/\/www.facebook.com\/britishschoolbarcelonacastelldefels\/","article_modified_time":"2026-06-05T10:53:42+00:00","og_image":[{"width":1116,"height":550,"url":"https:\/\/www.britishschoolbarcelona.com\/wp-content\/uploads\/sites\/76\/2026\/06\/eco-comms.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@BSB_Barcelona","twitter_misc":{"Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.britishschoolbarcelona.com\/es\/noticias-escolares\/creando-un-futuro-sostenible-el-camino-de-bsb\/#article","isPartOf":{"@id":"https:\/\/www.britishschoolbarcelona.com\/es\/noticias-escolares\/creando-un-futuro-sostenible-el-camino-de-bsb\/"},"author":{"name":"alejandroarraez","@id":"https:\/\/www.britishschoolbarcelona.com\/es\/#\/schema\/person\/795d1b75cffe8dc803898f92e5bd0549"},"headline":"Creando un futuro sostenible: el camino de BSB","datePublished":"2026-06-05T10:53:40+00:00","dateModified":"2026-06-05T10:53:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.britishschoolbarcelona.com\/es\/noticias-escolares\/creando-un-futuro-sostenible-el-camino-de-bsb\/"},"wordCount":800,"publisher":{"@id":"https:\/\/www.britishschoolbarcelona.com\/es\/#organization"},"image":{"@id":"https:\/\/www.britishschoolbarcelona.com\/es\/noticias-escolares\/creando-un-futuro-sostenible-el-camino-de-bsb\/#primaryimage"},"thumbnailUrl":"https:\/\/www.britishschoolbarcelona.com\/wp-content\/uploads\/sites\/76\/2026\/06\/eco-comms.png","inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.britishschoolbarcelona.com\/es\/noticias-escolares\/creando-un-futuro-sostenible-el-camino-de-bsb\/","url":"https:\/\/www.britishschoolbarcelona.com\/es\/noticias-escolares\/creando-un-futuro-sostenible-el-camino-de-bsb\/","name":"Creando un futuro sostenible: el camino de BSB - British School of Barcelona","isPartOf":{"@id":"https:\/\/www.britishschoolbarcelona.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.britishschoolbarcelona.com\/es\/noticias-escolares\/creando-un-futuro-sostenible-el-camino-de-bsb\/#primaryimage"},"image":{"@id":"https:\/\/www.britishschoolbarcelona.com\/es\/noticias-escolares\/creando-un-futuro-sostenible-el-camino-de-bsb\/#primaryimage"},"thumbnailUrl":"https:\/\/www.britishschoolbarcelona.com\/wp-content\/uploads\/sites\/76\/2026\/06\/eco-comms.png","datePublished":"2026-06-05T10:53:40+00:00","dateModified":"2026-06-05T10:53:42+00:00","description":"En The British School of Barcelona reconocemos que nuestro alumnado ya se ve afectado por el cambio clim\u00e1tico y debe estar equipado con las habilidades y la mentalidad necesarias para prosperar en un mundo m\u00e1s sostenible.","breadcrumb":{"@id":"https:\/\/www.britishschoolbarcelona.com\/es\/noticias-escolares\/creando-un-futuro-sostenible-el-camino-de-bsb\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.britishschoolbarcelona.com\/es\/noticias-escolares\/creando-un-futuro-sostenible-el-camino-de-bsb\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.britishschoolbarcelona.com\/es\/noticias-escolares\/creando-un-futuro-sostenible-el-camino-de-bsb\/#primaryimage","url":"https:\/\/www.britishschoolbarcelona.com\/wp-content\/uploads\/sites\/76\/2026\/06\/eco-comms.png","contentUrl":"https:\/\/www.britishschoolbarcelona.com\/wp-content\/uploads\/sites\/76\/2026\/06\/eco-comms.png","width":1116,"height":550},{"@type":"BreadcrumbList","@id":"https:\/\/www.britishschoolbarcelona.com\/es\/noticias-escolares\/creando-un-futuro-sostenible-el-camino-de-bsb\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.britishschoolbarcelona.com\/es\/"},{"@type":"ListItem","position":2,"name":"Noticias Escolares","item":"https:\/\/www.britishschoolbarcelona.com\/es\/noticias-escolares\/"},{"@type":"ListItem","position":3,"name":"Creando un futuro sostenible: el camino de BSB"}]},{"@type":"WebSite","@id":"https:\/\/www.britishschoolbarcelona.com\/es\/#website","url":"https:\/\/www.britishschoolbarcelona.com\/es\/","name":"British School of Barcelona","description":"The British School of Barcelona is a private international school in Barcelona, Spain. We deliver the British curriculum &amp; IB. Visit us!","publisher":{"@id":"https:\/\/www.britishschoolbarcelona.com\/es\/#organization"},"alternateName":"BSB","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.britishschoolbarcelona.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.britishschoolbarcelona.com\/es\/#organization","name":"The British School of Barcelona","alternateName":"BSB","url":"https:\/\/www.britishschoolbarcelona.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.britishschoolbarcelona.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.britishschoolbarcelona.com\/wp-content\/uploads\/sites\/76\/2023\/01\/BSB-logo.png","contentUrl":"https:\/\/www.britishschoolbarcelona.com\/wp-content\/uploads\/sites\/76\/2023\/01\/BSB-logo.png","width":1920,"height":1357,"caption":"The British School of Barcelona"},"image":{"@id":"https:\/\/www.britishschoolbarcelona.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/britishschoolbarcelonacastelldefels\/","https:\/\/x.com\/BSB_Barcelona","https:\/\/www.instagram.com\/britishschoolbarcelona\/","https:\/\/www.youtube.com\/channel\/UC-Cc996mIB8CwmapwNYQKvg","https:\/\/es.linkedin.com\/school\/british-school-of-barcelona\/"]},{"@type":"Person","@id":"https:\/\/www.britishschoolbarcelona.com\/es\/#\/schema\/person\/795d1b75cffe8dc803898f92e5bd0549","name":"alejandroarraez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/340d82f184ee74afef95c58a3c8b8aaccf3c9236f188fda15f2c3bc5c4f6e340?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/340d82f184ee74afef95c58a3c8b8aaccf3c9236f188fda15f2c3bc5c4f6e340?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/340d82f184ee74afef95c58a3c8b8aaccf3c9236f188fda15f2c3bc5c4f6e340?s=96&d=mm&r=g","caption":"alejandroarraez"},"url":"https:\/\/www.britishschoolbarcelona.com\/es\/author\/alejandroarraez\/"}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.britishschoolbarcelona.com\/es\/wp-json\/wp\/v2\/school_news\/77849","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.britishschoolbarcelona.com\/es\/wp-json\/wp\/v2\/school_news"}],"about":[{"href":"https:\/\/www.britishschoolbarcelona.com\/es\/wp-json\/wp\/v2\/types\/school_news"}],"author":[{"embeddable":true,"href":"https:\/\/www.britishschoolbarcelona.com\/es\/wp-json\/wp\/v2\/users\/480"}],"version-history":[{"count":2,"href":"https:\/\/www.britishschoolbarcelona.com\/es\/wp-json\/wp\/v2\/school_news\/77849\/revisions"}],"predecessor-version":[{"id":77853,"href":"https:\/\/www.britishschoolbarcelona.com\/es\/wp-json\/wp\/v2\/school_news\/77849\/revisions\/77853"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.britishschoolbarcelona.com\/es\/wp-json\/wp\/v2\/media\/77846"}],"wp:attachment":[{"href":"https:\/\/www.britishschoolbarcelona.com\/es\/wp-json\/wp\/v2\/media?parent=77849"}],"wp:term":[{"taxonomy":"news-category","embeddable":true,"href":"https:\/\/www.britishschoolbarcelona.com\/es\/wp-json\/wp\/v2\/news-category?post=77849"},{"taxonomy":"news-tag","embeddable":true,"href":"https:\/\/www.britishschoolbarcelona.com\/es\/wp-json\/wp\/v2\/news-tag?post=77849"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}